{"id":4220,"date":"2026-04-11T10:21:30","date_gmt":"2026-04-11T14:21:30","guid":{"rendered":"https:\/\/srh.fiu.edu\/home\/?post_type=events&#038;p=4220"},"modified":"2026-04-11T10:21:32","modified_gmt":"2026-04-11T14:21:32","slug":"deep-forensics-a-conversation-on-disappearance-technology-and-layered-violence-in-mexico","status":"publish","type":"events","link":"https:\/\/srh.fiu.edu\/home\/events\/deep-forensics-a-conversation-on-disappearance-technology-and-layered-violence-in-mexico\/","title":{"rendered":"Deep Forensics: A Conversation on Disappearance, Technology, and Layered Violence in Mexico"},"content":{"rendered":"","protected":false},"featured_media":0,"parent":0,"template":"","meta":{"_acf_changed":true,"_piecal_is_event":true,"_piecal_start_date":"2026-04-15T10:21:19","_piecal_end_date":"2026-04-15T10:21:21","_piecal_is_allday":true},"event-categories":[],"event-tags":[],"featured-events":[],"class_list":["post-4220","events","type-events","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/srh.fiu.edu\/home\/wp-json\/wp\/v2\/events\/4220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/srh.fiu.edu\/home\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/srh.fiu.edu\/home\/wp-json\/wp\/v2\/types\/events"}],"wp:attachment":[{"href":"https:\/\/srh.fiu.edu\/home\/wp-json\/wp\/v2\/media?parent=4220"}],"wp:term":[{"taxonomy":"event-categories","embeddable":true,"href":"https:\/\/srh.fiu.edu\/home\/wp-json\/wp\/v2\/event-categories?post=4220"},{"taxonomy":"event-tags","embeddable":true,"href":"https:\/\/srh.fiu.edu\/home\/wp-json\/wp\/v2\/event-tags?post=4220"},{"taxonomy":"featured-events","embeddable":true,"href":"https:\/\/srh.fiu.edu\/home\/wp-json\/wp\/v2\/featured-events?post=4220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}