{"id":4183,"date":"2026-03-27T12:30:11","date_gmt":"2026-03-27T16:30:11","guid":{"rendered":"https:\/\/srh.fiu.edu\/home\/?post_type=events&#038;p=4183"},"modified":"2026-03-27T12:30:14","modified_gmt":"2026-03-27T16:30:14","slug":"richard-lapper-in-dc-lula-and-brazils-2026-elections","status":"publish","type":"events","link":"https:\/\/srh.fiu.edu\/home\/events\/richard-lapper-in-dc-lula-and-brazils-2026-elections\/","title":{"rendered":"Richard Lapper in DC: Lula and Brazil&#8217;s 2026 elections"},"content":{"rendered":"","protected":false},"featured_media":0,"parent":0,"template":"","meta":{"_acf_changed":true,"_piecal_is_event":true,"_piecal_start_date":"2026-04-28T12:30:00","_piecal_end_date":"2026-04-28T12:30:04","_piecal_is_allday":true},"event-categories":[],"event-tags":[],"featured-events":[],"class_list":["post-4183","events","type-events","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/srh.fiu.edu\/home\/wp-json\/wp\/v2\/events\/4183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/srh.fiu.edu\/home\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/srh.fiu.edu\/home\/wp-json\/wp\/v2\/types\/events"}],"wp:attachment":[{"href":"https:\/\/srh.fiu.edu\/home\/wp-json\/wp\/v2\/media?parent=4183"}],"wp:term":[{"taxonomy":"event-categories","embeddable":true,"href":"https:\/\/srh.fiu.edu\/home\/wp-json\/wp\/v2\/event-categories?post=4183"},{"taxonomy":"event-tags","embeddable":true,"href":"https:\/\/srh.fiu.edu\/home\/wp-json\/wp\/v2\/event-tags?post=4183"},{"taxonomy":"featured-events","embeddable":true,"href":"https:\/\/srh.fiu.edu\/home\/wp-json\/wp\/v2\/featured-events?post=4183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}